{"id":111,"date":"2023-09-28T17:39:24","date_gmt":"2023-09-28T15:39:24","guid":{"rendered":"https:\/\/et-musique.fr\/?page_id=111"},"modified":"2023-09-28T17:40:01","modified_gmt":"2023-09-28T15:40:01","slug":"larbre-des-notes","status":"publish","type":"page","link":"https:\/\/et-musique.fr\/index.php\/un-peu-de-theorie\/larbre-des-notes\/","title":{"rendered":"L&rsquo;arbre des notes"},"content":{"rendered":"<p><iframe loading=\"lazy\" title=\"YouTube video player\" src=\"\/\/www.youtube.com\/embed\/s2l6REVaS08?si=zvAZm9IpSs_Li6Xc\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":102,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-111","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/et-musique.fr\/index.php\/wp-json\/wp\/v2\/pages\/111","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/et-musique.fr\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/et-musique.fr\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/et-musique.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/et-musique.fr\/index.php\/wp-json\/wp\/v2\/comments?post=111"}],"version-history":[{"count":1,"href":"https:\/\/et-musique.fr\/index.php\/wp-json\/wp\/v2\/pages\/111\/revisions"}],"predecessor-version":[{"id":112,"href":"https:\/\/et-musique.fr\/index.php\/wp-json\/wp\/v2\/pages\/111\/revisions\/112"}],"up":[{"embeddable":true,"href":"https:\/\/et-musique.fr\/index.php\/wp-json\/wp\/v2\/pages\/102"}],"wp:attachment":[{"href":"https:\/\/et-musique.fr\/index.php\/wp-json\/wp\/v2\/media?parent=111"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}