{"id":770,"date":"2024-07-19T15:01:47","date_gmt":"2024-07-19T13:01:47","guid":{"rendered":"https:\/\/et-musique.fr\/?page_id=770"},"modified":"2025-05-06T16:57:01","modified_gmt":"2025-05-06T14:57:01","slug":"je-mentraine-1c4","status":"publish","type":"page","link":"https:\/\/et-musique.fr\/index.php\/je-mentraine-1c4\/","title":{"rendered":"Je m&rsquo;entraine &#8230; 1C 4"},"content":{"rendered":"<p style=\"text-align: center;\"><strong><span style=\"font-size: 24pt;\">Je m&rsquo;entraine \u00e0 la reconnaissance des intervalles<\/span><br \/>\n<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 18pt;\"><strong>Fin de cycle 1<\/strong><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 14pt;\"><a href=\"https:\/\/et-musique.fr\/index.php\/secondes-mineures-majeures\/\" target=\"_blank\" rel=\"noopener\">Seconde mineure ou Majeure ?<\/a><\/span><\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/et-musique.fr\/index.php\/je-mentraine-a-la-reconnaissance-des-intervalles\/seconde-ou-tierce-majeure\/\" target=\"_blank\" rel=\"noopener\"><span style=\"font-size: 14pt;\">Seconde Majeure ou tierce Majeure ?<\/span><\/a><\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/et-musique.fr\/index.php\/je-mentraine-a-la-reconnaissance-des-intervalles\/tierces-mineures-majeures\/\" target=\"_blank\" rel=\"noopener\"><span style=\"font-size: 14pt;\">Tierce mineure ou Majeure ?<\/span><\/a><\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/et-musique.fr\/index.php\/je-mentraine-a-la-reconnaissance-des-intervalles\/tous-les-intervalles-de-seconde-ou-de-tierce\/\" target=\"_blank\" rel=\"noopener\"><span style=\"font-size: 14pt;\">Tous les intervalles de seconde et de tierce<\/span><\/a><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 14pt;\">Quarte juste, quinte juste ou octave juste ?<\/span><\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/et-musique.fr\/index.php\/je-mentraine-a-la-reconnaissance-des-intervalles\/melange-seconde-tierce-quarte-quinte-et-octave\/\" target=\"_blank\" rel=\"noopener\"><span style=\"font-size: 14pt;\">M\u00e9lange seconde, tierce, quarte, quinte et octave<\/span><\/a><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 24pt;\"><strong>Je m&rsquo;entraine \u00e0 la reconnaissance rythmique<\/strong><\/span><\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/et-musique.fr\/index.php\/je-mentraine-a-la-reconnaissance-des-intervalles\/releve-rythmique-binaire\/\" target=\"_blank\" rel=\"noopener\"><span style=\"font-size: 14pt;\">Dict\u00e9e rythmique binaire<\/span><\/a><\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/et-musique.fr\/index.php\/je-mentraine-a-la-reconnaissance-des-intervalles\/dictee-rythmique-ternaire\/\" target=\"_blank\" rel=\"noopener\"><span style=\"font-size: 14pt;\">Dict\u00e9e rythmique ternaire<\/span><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Je m&rsquo;entraine \u00e0 la reconnaissance des intervalles &nbsp; Fin de cycle 1 Seconde mineure ou Majeure ? Seconde Majeure ou tierce Majeure ? Tierce mineure ou Majeure ? Tous les intervalles de seconde et de tierce Quarte juste, quinte juste &hellip; <\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-770","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/et-musique.fr\/index.php\/wp-json\/wp\/v2\/pages\/770","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/et-musique.fr\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/et-musique.fr\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/et-musique.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/et-musique.fr\/index.php\/wp-json\/wp\/v2\/comments?post=770"}],"version-history":[{"count":25,"href":"https:\/\/et-musique.fr\/index.php\/wp-json\/wp\/v2\/pages\/770\/revisions"}],"predecessor-version":[{"id":1198,"href":"https:\/\/et-musique.fr\/index.php\/wp-json\/wp\/v2\/pages\/770\/revisions\/1198"}],"wp:attachment":[{"href":"https:\/\/et-musique.fr\/index.php\/wp-json\/wp\/v2\/media?parent=770"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}