{"id":13,"count":1,"description":"","link":"https:\/\/et-musique.fr\/index.php\/events\/categorie\/sortie-pedagogique-autres-activites\/","name":"Sortie p\u00e9dagogique\/ autres activit\u00e9s","slug":"sortie-pedagogique-autres-activites","taxonomy":"tribe_events_cat","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/et-musique.fr\/index.php\/wp-json\/wp\/v2\/tribe_events_cat\/13","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/et-musique.fr\/index.php\/wp-json\/wp\/v2\/tribe_events_cat"}],"about":[{"href":"https:\/\/et-musique.fr\/index.php\/wp-json\/wp\/v2\/taxonomies\/tribe_events_cat"}],"wp:post_type":[{"href":"https:\/\/et-musique.fr\/index.php\/wp-json\/wp\/v2\/tribe_events?tribe_events_cat=13"},{"href":"https:\/\/et-musique.fr\/index.php\/wp-json\/wp\/v2\/tec_calendar_embed?tribe_events_cat=13"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}